{"id":2822,"date":"2018-09-14T07:58:19","date_gmt":"2018-09-14T07:58:19","guid":{"rendered":"https:\/\/vella.sempreviva.cat\/profesores\/"},"modified":"2025-07-23T14:23:17","modified_gmt":"2025-07-23T14:23:17","slug":"profesores","status":"publish","type":"page","link":"https:\/\/vella.sempreviva.cat\/es\/profesores\/","title":{"rendered":"Profesores"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto width_full with_img\"><div class=\"l-section-img\" style=\"background-image: url(https:\/\/vella.sempreviva.cat\/wp-content\/uploads\/2018\/09\/181.jpg);background-repeat: no-repeat;\" data-img-width=\"2000\" data-img-height=\"684\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_middle\"><div class=\"vc_col-sm-6 wpb_column vc_column_container has-fill\"><div class=\"vc_column-inner  vc_custom_1536314544622\"><div class=\"wpb_wrapper\">[vc_empty_space height=\u00bb200px\u00bb]<div class=\"g-cols wpb_row type_default valign_top vc_inner \"><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"vc_col-sm-8 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_text_column \">\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<h1 class=\"timetable-title\" style=\"text-align: right;\"><strong><img loading=\"lazy\" class=\"alignnone wp-image-85\" src=\"https:\/\/vella.sempreviva.cat\/wp-content\/uploads\/2018\/09\/hoja.png\" alt=\"\" width=\"20\" height=\"30\" \/><\/strong><br \/>\nProfesores<\/h1>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div>[vc_empty_space]<\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row type_default valign_top vc_inner \"><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-person layout_trendy with_desc\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\"><div class=\"w-person-image\"><img src=\"https:\/\/vella.sempreviva.cat\/wp-content\/uploads\/2018\/09\/MG_2190-3-350x350.jpg\" width=\"350\" height=\"350\" alt=\"Neus Caballer\" itemprop=\"image\"><\/div><div class=\"w-person-content\"><h4 class=\"w-person-name\" itemprop=\"name\"><span>Neus Caballer<\/span><\/h4><div class=\"w-person-role\" itemprop=\"jobTitle\">Yoga, Yoga A\u00e9reo, Mindfulness, ...<\/div><\/div><div class=\"w-person-content-alt\"><div class=\"w-person-description\" itemprop=\"description\">N\u00ba ROPEC 31477<br \/>\nRYS 500h Formaci\u00f3n Maestr\u00eda de Yoga<br \/>\n30h \u00c9tica del Instructor de Yoga &#8211; Yoga Sutras<br \/>\n50h Yoga A\u00e9reo<br \/>\nMindfulness<br \/>\nYoga Kids<br \/>\nReikista, Aromaterapeuta, cuentacuentos, estimuladora multisensorial<br \/>\nFormadora T\u00e9cnicas de relajaci\u00f3n, Mindfulness, Gesti\u00f3n del Estr\u00e9s, &#8230;<br \/>\nTallerista Risoterapias, Biodanzas, &#8230;<br \/>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-person layout_trendy with_desc\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/Person\"><div class=\"w-person-image\"><img src=\"https:\/\/vella.sempreviva.cat\/wp-content\/uploads\/2019\/09\/DSC_0078-350x350.jpg\" width=\"350\" height=\"350\" alt=\"Rosa Gallego\" itemprop=\"image\"><\/div><div class=\"w-person-content\"><h4 class=\"w-person-name\" itemprop=\"name\"><span>Rosa Gallego<\/span><\/h4><div class=\"w-person-role\" itemprop=\"jobTitle\">Yoga, Yoga A\u00e9reo, Hipopresivos,...<\/div><\/div><div class=\"w-person-content-alt\"><div class=\"w-person-description\" itemprop=\"description\">RYS 200h Ashtanga Yoga<br \/>\nRYS 50h Yoga A\u00e9reo<br \/>\nHipopresivos<br \/>\nYoga Kids &amp; Family<br \/>\n600h M\u00e1ster en Inteligencia Emocional<br \/>\nFormadora T\u00e9cnicas de Relajaci\u00f3n, Gesti\u00f3n del Estr\u00e9s, &#8230;<br \/>\nDanza Oriental<\/div><\/div><\/div><\/div><\/div><\/div><\/div>[vc_empty_space height=\u00bb54px\u00bb]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row type_default valign_top\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\r\n\t<div class=\"wpb_text_column \">\r\n\t\t<div class=\"wpb_wrapper\">\r\n\t\t\t<p data-start=\"0\" data-end=\"221\">En <em data-start=\"2\" data-end=\"14\">Sempreviva<\/em> contamos con un equipo de profesionales comprometidas, creativas y profundamente conectadas con su camino. Hoy os presentamos dos de las gu\u00edas que hacen posible este espacio de crecimiento: <strong data-start=\"201\" data-end=\"209\">Neus<\/strong> y <strong data-start=\"212\" data-end=\"220\">Rosa<\/strong> .<\/p>\n<p data-start=\"223\" data-end=\"859\"><strong data-start=\"223\" data-end=\"231\">Neus<\/strong> es instructora de yoga con el n\u00famero ROPEC 31477 y formaci\u00f3n RYS 500h en <em data-start=\"304\" data-end=\"322\">Maestr\u00eda de Yoga<\/em> . Con m\u00e1s de 30h de especializaci\u00f3n en \u00e9tica del yoga y el estudio de los <em data-start=\"391\" data-end=\"404\">Yoga Sutras<\/em> , y 50h en <em data-start=\"415\" data-end=\"426\" data-is-only-node=\"\">Yoga Aeri<\/em> , su pr\u00e1ctica combina t\u00e9cnica, sensibilidad y presencia. Es tambi\u00e9n instructora de <em data-start=\"512\" data-end=\"525\">Mindfulness<\/em> , <em data-start=\"527\" data-end=\"538\">Yoga Kids<\/em> , <em data-start=\"540\" data-end=\"550\">Reikista<\/em> , aromaterapeuta, cuentacuentos y estimuladora multisensorial. Su vocaci\u00f3n pedag\u00f3gica le ha llevado a formar personas en t\u00e9cnicas de relajaci\u00f3n, gesti\u00f3n del estr\u00e9s y <em data-start=\"717\" data-end=\"730\">Mindfulness<\/em> , as\u00ed como a dinamizar talleres vivenciales como la risoterapia o la biodanza. Neus es energ\u00eda c\u00e1lida, acogedora e inspiradora.<\/p>\n<p data-start=\"861\" data-end=\"1397\"><strong data-start=\"861\" data-end=\"869\">Rosa<\/strong> es instructora certificada con formaci\u00f3n RYS 200h en <em data-start=\"922\" data-end=\"937\">Ashtanga Yoga<\/em> , y RYS 50h en <em data-start=\"952\" data-end=\"963\">Yoga A\u00e9reo<\/em> . Tambi\u00e9n es especialista en <em data-start=\"990\" data-end=\"1004\" data-is-only-node=\"\">Hipopresivos<\/em> , <em data-start=\"1006\" data-end=\"1026\">Yoga Kids &amp; Family<\/em> , y combina cuerpo y emoci\u00f3n con una s\u00f3lida formaci\u00f3n de 600h en <em data-start=\"1086\" data-end=\"1112\">Inteligencia Emocional<\/em> . Es formadora en t\u00e9cnicas de relajaci\u00f3n y gesti\u00f3n del estr\u00e9s, destacando por su conexi\u00f3n con la danza, especialmente la <em data-start=\"1236\" data-end=\"1252\">Danza Oriental<\/em> , que aporta una dimensi\u00f3n expresiva y femenina a su acompa\u00f1amiento. Con Rosa, la pr\u00e1ctica se convierte en un espacio de empoderamiento y escucha interior.<\/p>\n<p data-start=\"1399\" data-end=\"1594\" data-is-last-node=\"\" data-is-only-node=\"\">Juntas, Neus y Rosa ofrecen un abanico de pr\u00e1cticas enriquecedoras, sensibles y transformadoras. En <em data-start=\"1505\" data-end=\"1517\">Sempreviva<\/em> te acompa\u00f1an desde la pasi\u00f3n, el respeto y la vocaci\u00f3n profunda de cuidar.<\/p>\n\r\n\t\t<\/div>\r\n\t<\/div>\r\n<\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_empty_space height=\"200px\"] Profesores [vc_empty_space]Neus CaballerYoga, Yoga A\u00e9reo, Mindfulness, ...N\u00ba ROPEC 31477 RYS 500h Formaci\u00f3n Maestr\u00eda de Yoga 30h \u00c9tica del Instructor de Yoga - Yoga Sutras 50h Yoga A\u00e9reo Mindfulness Yoga Kids Reikista, Aromaterapeuta, cuentacuentos, estimuladora multisensorial Formadora T\u00e9cnicas de relajaci\u00f3n, Mindfulness, Gesti\u00f3n del Estr\u00e9s, ... Tallerista Risoterapias, Biodanzas, ... Rosa GallegoYoga, Yoga A\u00e9reo, Hipopresivos,...RYS...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"om_disable_all_campaigns":false,"pmpro_default_level":""},"aioseo_notices":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/PaeZJ6-Jw","_links":{"self":[{"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/pages\/2822"}],"collection":[{"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/comments?post=2822"}],"version-history":[{"count":3,"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/pages\/2822\/revisions"}],"predecessor-version":[{"id":2867,"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/pages\/2822\/revisions\/2867"}],"wp:attachment":[{"href":"https:\/\/vella.sempreviva.cat\/es\/wp-json\/wp\/v2\/media?parent=2822"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}